{"id":2132,"date":"2025-07-11T09:04:26","date_gmt":"2025-07-11T09:04:26","guid":{"rendered":"https:\/\/ycpcbs.com\/?page_id=2132"},"modified":"2025-11-03T09:50:41","modified_gmt":"2025-11-03T09:50:41","slug":"contact","status":"publish","type":"page","link":"https:\/\/ycpcbs.com\/hu\/contact\/","title":{"rendered":"Kapcsolat"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2132\" class=\"elementor elementor-2132\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cb114e4 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3cb114e4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c0c81c3\" data-id=\"7c0c81c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b845f8d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7b845f8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kapcsolatunk<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c845b1f elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"7c845b1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u0151oldal<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kapcsolat<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6af05541 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6af05541\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec00ed5\" data-id=\"ec00ed5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-13cc3735 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13cc3735\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6c74bdbd elementor-invisible\" data-id=\"6c74bdbd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:400,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d2df038 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6d2df038\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tC\u00edm\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBogang K\u00f6z\u00f6ss\u00e9g, Shajing utca, Baoan ker\u00fclet, Shenzhen, Guangdong, K\u00edna\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2a6fa4e8 elementor-invisible\" data-id=\"2a6fa4e8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:500,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58064246 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"58064246\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTelefon\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t+86-0755-2709-5550 <br> +86-16675190295\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1674d02c elementor-invisible\" data-id=\"1674d02c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:600,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d625d3a elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2d625d3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tsales@ycelectronic.com <br> sales@ycelectronic.com\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1417826d elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1417826d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-711d7acf\" data-id=\"711d7acf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ab9f26b elementor-widget elementor-widget-google_maps\" data-id=\"3ab9f26b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Shajing%20Street%2C%20Baoan%20District%2C%20Shenzhen%2C%20Guangdong%2C%20China&#038;t=m&#038;z=14&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Shajing utca, Baoan ker\u00fclet, Shenzhen, Guangdong, K\u00edna\"\n\t\t\t\t\taria-label=\"Shajing utca, Baoan ker\u00fclet, Shenzhen, Guangdong, K\u00edna\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6dab5ad7\" data-id=\"6dab5ad7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b466ea elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-elementskit-header-info\" data-id=\"5b466ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"elementskit-header-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <ul class=\"ekit-header-info\">\n                                    <li>\n                            <a > \n                                <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>                                Kapcsolat                            <\/a>\n                        <\/li>\n\n                            <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42aaa899 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"42aaa899\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kapcsolatfelv\u00e9tel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c082b89 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1c082b89\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>K\u00e9rj\u00fck, b\u00e1tran l\u00e9pjen vel\u00fcnk kapcsolatba.\nA lehet\u0151 leghamarabb v\u00e1laszolunk.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02170ac elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"02170ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;30&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"\u00daj \u0171rlap\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"2132\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"02170ac\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"CONTACT\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"2132\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"N\u00e9v\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"\u00dczenet\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-30 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">K\u00fcld\u00e9s<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"hu\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bb35a7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bb35a7d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61fb0c9c\" data-id=\"61fb0c9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44e10cc2 elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-elementskit-header-info\" data-id=\"44e10cc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"elementskit-header-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <ul class=\"ekit-header-info\">\n                                    <li>\n                            <a > \n                                <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>                                Gyakran Ism\u00e9telt K\u00e9rd\u00e9sek                            <\/a>\n                        <\/li>\n\n                            <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4873c753 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4873c753\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gyakran Ism\u00e9telt K\u00e9rd\u00e9sek<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-745bcee9 elementor-invisible elementor-widget elementor-widget-elementskit-accordion\" data-id=\"745bcee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a045fc18e897\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-745bcee9\">\n                        <a href=\"#collapse-a6e33056a045fc18e897\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-a6e33056a045fc18e897\" aria-expanded=\"true\" aria-controls=\"Collapse-a6e33056a045fc18e897\">\n                            \n                            <span class=\"ekit-accordion-title\">Milyen f\u00e1jlokat kell biztos\u00edtanom a PCB gy\u00e1rt\u00e1s\u00e1hoz?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-a6e33056a045fc18e897\" class=\"show collapse\" aria-labelledby=\"primaryHeading-0-745bcee9\" data-parent=\"#accordion-6a045fc18e897\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>K\u00e9rj\u00fck, biztos\u00edtson Gerber f\u00e1jlokat (RS-274X form\u00e1tum), furatf\u00e1jlt (Excellon), \u00e9s egy BOM-ot, ha \u00f6sszeszerel\u00e9sre van sz\u00fcks\u00e9g.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-745bcee9\">\n                        <a href=\"#collapse-ed795eb6a045fc18e897\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-ed795eb6a045fc18e897\" aria-expanded=\"false\" aria-controls=\"Collapse-ed795eb6a045fc18e897\">\n                            \n                            <span class=\"ekit-accordion-title\">Kaphatok ingyenes mint\u00e1t, miel\u0151tt nagy t\u00e9telben rendeln\u00e9k?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-ed795eb6a045fc18e897\" class=\"collapse\" aria-labelledby=\"primaryHeading-1-745bcee9\" data-parent=\"#accordion-6a045fc18e897\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Igen, els\u0151 v\u00e1s\u00e1rl\u00f3inknak ingyenes PCB mint\u00e1kat k\u00edn\u00e1lunk. Csak a sz\u00e1ll\u00edt\u00e1si k\u00f6lts\u00e9get kell fedeznie.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-745bcee9\">\n                        <a href=\"#collapse-3ec797f6a045fc18e897\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3ec797f6a045fc18e897\" aria-expanded=\"false\" aria-controls=\"Collapse-3ec797f6a045fc18e897\">\n                            \n                            <span class=\"ekit-accordion-title\">Milyen t\u00edpus\u00fa PCB-ket gy\u00e1rtanak?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3ec797f6a045fc18e897\" class=\"collapse\" aria-labelledby=\"primaryHeading-2-745bcee9\" data-parent=\"#accordion-6a045fc18e897\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Egyszeres, k\u00e9tszeres \u00e9s t\u00f6bb r\u00e9teg\u0171 nyomtatott \u00e1ramk\u00f6r\u00f6ket (ak\u00e1r 20 r\u00e9tegig) gy\u00e1rtunk, bele\u00e9rtve az FR4-et, alum\u00edniumot, r\u00e9z alapot, HDI-t \u00e9s magas frekvenci\u00e1j\u00fa lapokat.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-745bcee9\">\n                        <a href=\"#collapse-e752d5a6a045fc18e897\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-e752d5a6a045fc18e897\" aria-expanded=\"false\" aria-controls=\"Collapse-e752d5a6a045fc18e897\">\n                            \n                            <span class=\"ekit-accordion-title\">Mi a szok\u00e1sos gy\u00e1rt\u00e1si \u00e1tfut\u00e1si ideje?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-e752d5a6a045fc18e897\" class=\"collapse\" aria-labelledby=\"primaryHeading-3-745bcee9\" data-parent=\"#accordion-6a045fc18e897\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Protot\u00edpus PCB-k: 2\u20135 munkanap.\nT\u00f6megtermel\u00e9s: 7\u201312 munkanap. S\u00fcrg\u0151s megrendel\u00e9seket gyors\u00edthatunk.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-745bcee9\">\n                        <a href=\"#collapse-1e1dab06a045fc18e897\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-1e1dab06a045fc18e897\" aria-expanded=\"false\" aria-controls=\"Collapse-1e1dab06a045fc18e897\">\n                            \n                            <span class=\"ekit-accordion-title\">T\u00e1mogatja-e a PCB \u00f6sszeszerel\u00e9st (PCBA)?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-1e1dab06a045fc18e897\" class=\"collapse\" aria-labelledby=\"primaryHeading-4-745bcee9\" data-parent=\"#accordion-6a045fc18e897\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Igen, teljes k\u00f6r\u0171 PCB \u00f6sszeszerel\u00e9si szolg\u00e1ltat\u00e1sokat ny\u00fajtunk, bele\u00e9rtve az SMT-t, THT-t \u00e9s a funkcion\u00e1lis tesztel\u00e9st.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-745bcee9\">\n                        <a href=\"#collapse-6251b556a045fc18e897\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-6251b556a045fc18e897\" aria-expanded=\"false\" aria-controls=\"Collapse-6251b556a045fc18e897\">\n                            \n                            <span class=\"ekit-accordion-title\">Ellen\u0151rizheti-e a tervez\u00e9st gy\u00e1rt\u00e1s el\u0151tt?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-6251b556a045fc18e897\" class=\"collapse\" aria-labelledby=\"primaryHeading-5-745bcee9\" data-parent=\"#accordion-6a045fc18e897\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Igen, ingyenes DFM \u00e9s DFA ellen\u0151rz\u00e9seket k\u00edn\u00e1lunk, hogy biztos\u00edtsuk, a tervez\u00e9s k\u00e9szen \u00e1ll a gy\u00e1rt\u00e1sra \u00e9s az \u00f6sszeszerel\u00e9sre.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-745bcee9\">\n                        <a href=\"#collapse-aa6b65a6a045fc18e897\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-aa6b65a6a045fc18e897\" aria-expanded=\"false\" aria-controls=\"Collapse-aa6b65a6a045fc18e897\">\n                            \n                            <span class=\"ekit-accordion-title\">Mi a minim\u00e1lis rendel\u00e9si mennyis\u00e9g (MOQ)?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-aa6b65a6a045fc18e897\" class=\"collapse\" aria-labelledby=\"primaryHeading-6-745bcee9\" data-parent=\"#accordion-6a045fc18e897\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>T\u00e1mogatjuk az alacsony volumen\u0171 rendel\u00e9seket, kezdve 1 darabbal. Nincs MOQ a standard PCB-k eset\u00e9ben.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-7-745bcee9\">\n                        <a href=\"#collapse-d8cc0426a045fc18e897\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-d8cc0426a045fc18e897\" aria-expanded=\"false\" aria-controls=\"Collapse-d8cc0426a045fc18e897\">\n                            \n                            <span class=\"ekit-accordion-title\">Milyen fizet\u00e9si m\u00f3dokat fogad el?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-d8cc0426a045fc18e897\" class=\"collapse\" aria-labelledby=\"primaryHeading-7-745bcee9\" data-parent=\"#accordion-6a045fc18e897\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Elfogadjuk a T\/T (banki \u00e1tutal\u00e1s), PayPal \u00e9s Western Union fizet\u00e9seket.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Kapcsolatunk Otthoni kapcsolat C\u00edm Bogang k\u00f6z\u00f6ss\u00e9g, Shajing utca, Baoan ker\u00fclet, Shenzhen, Guangdong, K\u00edna Telefon +86-0755-2709-5550 +86-16675190295 E-mail sales@ycelectronic.com sales@ycelectronic.com Kapcsolat Vegye fel vel\u00fcnk a kapcsolatot K\u00e9rj\u00fck, b\u00e1tran l\u00e9pjen kapcsolatba vel\u00fcnk. A lehet\u0151 leghamarabb v\u00e1laszolunk. Gyakran ism\u00e9telt k\u00e9rd\u00e9sek Gyakran ism\u00e9telt k\u00e9rd\u00e9sek Milyen f\u00e1jlokat kell biztos\u00edtanom az PCB gy\u00e1rt\u00e1s\u00e1hoz? K\u00e9rj\u00fck, biztos\u00edtson Gerber f\u00e1jlokat [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_zeroy_edited":false,"_zeroy_last_edited":"","footnotes":""},"class_list":["post-2132","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ycpcbs.com\/hu\/wp-json\/wp\/v2\/pages\/2132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ycpcbs.com\/hu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ycpcbs.com\/hu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ycpcbs.com\/hu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ycpcbs.com\/hu\/wp-json\/wp\/v2\/comments?post=2132"}],"version-history":[{"count":21,"href":"https:\/\/ycpcbs.com\/hu\/wp-json\/wp\/v2\/pages\/2132\/revisions"}],"predecessor-version":[{"id":2868,"href":"https:\/\/ycpcbs.com\/hu\/wp-json\/wp\/v2\/pages\/2132\/revisions\/2868"}],"wp:attachment":[{"href":"https:\/\/ycpcbs.com\/hu\/wp-json\/wp\/v2\/media?parent=2132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}