{"id":2152,"date":"2025-07-11T10:55:47","date_gmt":"2025-07-11T10:55:47","guid":{"rendered":"https:\/\/ycpcbs.com\/?page_id=2152"},"modified":"2025-07-15T11:16:04","modified_gmt":"2025-07-15T11:16:04","slug":"product-detail","status":"publish","type":"page","link":"https:\/\/ycpcbs.com\/fi\/product-detail\/","title":{"rendered":"Tuotteen tiedot"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2152\" class=\"elementor elementor-2152\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c86a470 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7c86a470\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26e50e43\" data-id=\"26e50e43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1aef5c30 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1aef5c30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tuotteen tiedot<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c3c7a81 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"2c3c7a81\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Koti<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tuote<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b0b96aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b0b96aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7430f1dd\" data-id=\"7430f1dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f0ddf92 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f0ddf92\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-af5b123\" data-id=\"af5b123\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7eb5c6ae elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7eb5c6ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"451\" height=\"1024\" src=\"https:\/\/ycpcbs.com\/wp-content\/uploads\/2025\/07\/High-thermal-conductivity-LEDPCBA-aluminum-substrate\u9ad8\u5bfc\u70ed-LEDPCBA-\u94dd\u57fa\u677f-1-451x1024.jpg\" class=\"elementor-animation-grow attachment-large size-large wp-image-2067\" alt=\"Korkean l\u00e4mp\u00f6johtavuuden LED-PCBA alumiininen substraatti\" srcset=\"https:\/\/ycpcbs.com\/wp-content\/uploads\/2025\/07\/High-thermal-conductivity-LEDPCBA-aluminum-substrate\u9ad8\u5bfc\u70ed-LEDPCBA-\u94dd\u57fa\u677f-1-451x1024.jpg 451w, https:\/\/ycpcbs.com\/wp-content\/uploads\/2025\/07\/High-thermal-conductivity-LEDPCBA-aluminum-substrate\u9ad8\u5bfc\u70ed-LEDPCBA-\u94dd\u57fa\u677f-1-132x300.jpg 132w, https:\/\/ycpcbs.com\/wp-content\/uploads\/2025\/07\/High-thermal-conductivity-LEDPCBA-aluminum-substrate\u9ad8\u5bfc\u70ed-LEDPCBA-\u94dd\u57fa\u677f-1.jpg 616w\" sizes=\"(max-width: 451px) 100vw, 451px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7773bf7a\" data-id=\"7773bf7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f644bb elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-elementskit-header-info\" data-id=\"3f644bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"elementskit-header-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <ul class=\"ekit-header-info\">\n                                    <li>\n                            <a > \n                                <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>                                Kuuma Tuote                            <\/a>\n                        <\/li>\n\n                            <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-678e3aff elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"678e3aff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Korkean l\u00e4mm\u00f6njohtavuuden LED PCBA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-310d0a99 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"310d0a99\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Valmistettu alumiinipohjamateriaalista ja 2,0 W\/m\u00b7K l\u00e4mm\u00f6njohtavuuden erist\u00e4v\u00e4st\u00e4 kerroksesta, t\u00e4m\u00e4 LED PCBA tarjoaa erinomaisen l\u00e4mm\u00f6nhukan. Ominaisuuksiin kuuluvat 1 oz kuparipaksuus, yksikerroksinen rakenne ja pintak\u00e4sittelyvaihtoehdot kuten HASL tai ENIG. Ihanteellinen korkeatehoisille LED-valaistussovelluksille.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de2852 elementor-view-stacked elementor-widget__width-initial elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"de2852\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-shield\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLuotettava turvallisuus\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVakaat suorituskyky ja erinomainen l\u00e4mm\u00f6nhukka varmistavat turvallisen toiminnan kaikissa LED-valaistusj\u00e4rjestelmiss\u00e4.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0363ff elementor-view-stacked elementor-widget__width-initial elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"b0363ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:700}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-tags\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKilpailukykyiset hinnat\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSuurtuotanto ja suora tehtaan toimitus auttavat sinua saamaan korkealaatuisia LED-kerroksia parempaan hintaan.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c34e73c elementor-view-stacked elementor-widget__width-initial elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"5c34e73c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checked\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tJohdonmukainen laatu\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tJokainen levy k\u00e4y l\u00e4pi tiukan tarkastuksen taatakseen pitk\u00e4n k\u00e4ytt\u00f6i\u00e4n ja tasaisen valaistustehon.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f24ed2c elementor-widget elementor-widget-spacer\" data-id=\"5f24ed2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6d543 elementor-invisible elementor-widget elementor-widget-elementskit-progressbar\" data-id=\"f6d543\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"elementskit-progressbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <div class=\"waypoint-tigger\">\n            <div class=\"skillbar-group\" data-progress-bar=\"\">\n                <div class=\"single-skill-bar\">\n                                            <div class=\"skill-bar-content\">\n                            <span class=\"skill-title\">L\u00e4mm\u00f6nhukka<\/span>\n                        <\/div><!-- .skill-bar-content END -->\n                        <div class=\"skill-bar\">\n                            <div class=\"skill-track\">\n                                \n                                <div class=\"number-percentage-wraper\">\n                                    <span class=\"number-percentage\" data-value=\"95\" data-animation-duration=\"3500\">0<\/span>%\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div><!-- .skill-bar END -->\n                                    <\/div><!-- .single-skill-bar END -->\n            <\/div><!-- .skillbar-group END -->\n        <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52a6b069 elementor-invisible elementor-widget elementor-widget-elementskit-progressbar\" data-id=\"52a6b069\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"elementskit-progressbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <div class=\"waypoint-tigger\">\n            <div class=\"skillbar-group\" data-progress-bar=\"\">\n                <div class=\"single-skill-bar\">\n                                            <div class=\"skill-bar-content\">\n                            <span class=\"skill-title\">L\u00e4mm\u00f6njohtavuus<\/span>\n                        <\/div><!-- .skill-bar-content END -->\n                        <div class=\"skill-bar\">\n                            <div class=\"skill-track\">\n                                \n                                <div class=\"number-percentage-wraper\">\n                                    <span class=\"number-percentage\" data-value=\"94\" data-animation-duration=\"3500\">0<\/span>%\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div><!-- .skill-bar END -->\n                                    <\/div><!-- .single-skill-bar END -->\n            <\/div><!-- .skillbar-group END -->\n        <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b671c82 elementor-invisible elementor-widget elementor-widget-elementskit-progressbar\" data-id=\"3b671c82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"elementskit-progressbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <div class=\"waypoint-tigger\">\n            <div class=\"skillbar-group\" data-progress-bar=\"\">\n                <div class=\"single-skill-bar\">\n                                            <div class=\"skill-bar-content\">\n                            <span class=\"skill-title\">Materiaali luokka<\/span>\n                        <\/div><!-- .skill-bar-content END -->\n                        <div class=\"skill-bar\">\n                            <div class=\"skill-track\">\n                                \n                                <div class=\"number-percentage-wraper\">\n                                    <span class=\"number-percentage\" data-value=\"96\" data-animation-duration=\"3500\">0<\/span>%\n\n                                                                    <\/div>\n                            <\/div>\n                        <\/div><!-- .skill-bar END -->\n                                    <\/div><!-- .single-skill-bar END -->\n            <\/div><!-- .skillbar-group END -->\n        <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63ebdcd3 elementor-align-left elementor-mobile-align-left elementor-invisible elementor-widget elementor-widget-button\" data-id=\"63ebdcd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3NiIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tilaa nyt<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f51d5d7 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f51d5d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ecfb16c\" data-id=\"6ecfb16c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17f27ee1 elementor-widget elementor-widget-elementskit-video\" data-id=\"17f27ee1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"video-content\" data-video-player=\"[]\" data-video-setting=\"{&quot;videoVolume&quot;:&quot;horizontal&quot;,&quot;startVolume&quot;:0.8,&quot;videoType&quot;:&quot;iframe&quot;,&quot;videoClass&quot;:&quot;mfp-fade&quot;,&quot;videoStyle&quot;:&quot;popup&quot;,&quot;videoTypeName&quot;:&quot;youtube&quot;,&quot;autoplay&quot;:false,&quot;muted&quot;:false,&quot;loop&quot;:false}\">\n\t\t\t\n<a class=\"ekit_icon_button glow-ripple ekit-video-popup ekit-video-popup-btn\" href=\"https:\/\/www.youtube.com\/embed\/8_h4YYjUUOY?feature=oembed?playlist=8_h4YYjUUOY&amp;mute=0&amp;autoplay=0&amp;loop=no&amp;controls=0&amp;start=0&amp;end=\" aria-label=\"video-popup\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-play\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\n\t\t\t<\/a>\n\t\t\t\t\t\t\t<div class=\"ekit-hidden-icons\" hidden aria-hidden=\"true\">\n\t\t\t\t\t<i class=\"ekit-popup-close-icon icon icon-cancel\"><\/i>\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-978eff6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"978eff6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34435c52\" data-id=\"34435c52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f35bbfc elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-elementskit-header-info\" data-id=\"7f35bbfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"elementskit-header-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <ul class=\"ekit-header-info\">\n                                    <li>\n                            <a > \n                                <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>                                Usein kysytyt kysymykset                            <\/a>\n                        <\/li>\n\n                            <\/ul>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-829f2e4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"829f2e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Usein kysytyt kysymykset<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9fe223 elementor-invisible elementor-widget elementor-widget-elementskit-accordion\" data-id=\"d9fe223\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a045ff1e3765\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-d9fe223\">\n                        <a href=\"#collapse-a6e33056a045ff1e3765\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-a6e33056a045ff1e3765\" aria-expanded=\"true\" aria-controls=\"Collapse-a6e33056a045ff1e3765\">\n                            \n                            <span class=\"ekit-accordion-title\">Mit\u00e4 tiedostoja minun t\u00e4ytyy toimittaa PCB-valmistukseen?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-a6e33056a045ff1e3765\" class=\"show collapse\" aria-labelledby=\"primaryHeading-0-d9fe223\" data-parent=\"#accordion-6a045ff1e3765\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Toimita Gerber-tiedostot (RS-274X-muoto), poraustiedosto (Excellon) ja BOM, jos kokoonpano on tarpeen.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-d9fe223\">\n                        <a href=\"#collapse-ed795eb6a045ff1e3765\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-ed795eb6a045ff1e3765\" aria-expanded=\"false\" aria-controls=\"Collapse-ed795eb6a045ff1e3765\">\n                            \n                            <span class=\"ekit-accordion-title\">Voinko saada ilmaisen n\u00e4ytteen ennen suuremman tilauksen tekemist\u00e4?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-ed795eb6a045ff1e3765\" class=\"collapse\" aria-labelledby=\"primaryHeading-1-d9fe223\" data-parent=\"#accordion-6a045ff1e3765\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Kyll\u00e4, tarjoamme ilmaisia PCB-n\u00e4ytteit\u00e4 ensimm\u00e4ist\u00e4 kertaa ostaville asiakkaille. Sinun tarvitsee vain kattaa toimituskulut.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-d9fe223\">\n                        <a href=\"#collapse-3ec797f6a045ff1e3765\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3ec797f6a045ff1e3765\" aria-expanded=\"false\" aria-controls=\"Collapse-3ec797f6a045ff1e3765\">\n                            \n                            <span class=\"ekit-accordion-title\">Mit\u00e4 tyyppisi\u00e4 PCB:t\u00e4 valmistatte?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3ec797f6a045ff1e3765\" class=\"collapse\" aria-labelledby=\"primaryHeading-2-d9fe223\" data-parent=\"#accordion-6a045ff1e3765\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Valmistamme yksipuolisia, kaksoispuolisia ja monikerros-PCB:it\u00e4 (enint\u00e4\u00e4n 20 kerrosta), mukaan lukien FR4, alumiini, kuparipohja, HDI ja korkeataajuuslevyt.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-d9fe223\">\n                        <a href=\"#collapse-e752d5a6a045ff1e3765\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-e752d5a6a045ff1e3765\" aria-expanded=\"false\" aria-controls=\"Collapse-e752d5a6a045ff1e3765\">\n                            \n                            <span class=\"ekit-accordion-title\">Mik\u00e4 on tyypillinen toimitusaikasi tuotannolle?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-e752d5a6a045ff1e3765\" class=\"collapse\" aria-labelledby=\"primaryHeading-3-d9fe223\" data-parent=\"#accordion-6a045ff1e3765\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Prototyyppiset PCB:t: 2\u20135 ty\u00f6p\u00e4iv\u00e4\u00e4.\nMassatuotanto: 7\u201312 ty\u00f6p\u00e4iv\u00e4\u00e4. Kiireelliset tilaukset voidaan nopeuttaa.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-d9fe223\">\n                        <a href=\"#collapse-fa73ba46a045ff1e3765\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-fa73ba46a045ff1e3765\" aria-expanded=\"false\" aria-controls=\"Collapse-fa73ba46a045ff1e3765\">\n                            \n                            <span class=\"ekit-accordion-title\">Tukeeko teid\u00e4n PCB-kokoonpanoa (PCBA)?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-fa73ba46a045ff1e3765\" class=\"collapse\" aria-labelledby=\"primaryHeading-4-d9fe223\" data-parent=\"#accordion-6a045ff1e3765\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Kyll\u00e4, tarjoamme avaimet k\u00e4teen PCB-kokoonpanopalveluita, mukaan lukien SMT, THT ja toiminnallinen testaus.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-d9fe223\">\n                        <a href=\"#collapse-840f6776a045ff1e3765\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-840f6776a045ff1e3765\" aria-expanded=\"false\" aria-controls=\"Collapse-840f6776a045ff1e3765\">\n                            \n                            <span class=\"ekit-accordion-title\">Voitteko tarkistaa suunnitteluni ennen tuotantoa?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-840f6776a045ff1e3765\" class=\"collapse\" aria-labelledby=\"primaryHeading-5-d9fe223\" data-parent=\"#accordion-6a045ff1e3765\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Kyll\u00e4, tarjoamme ilmaiset DFM- ja DFA-tarkastukset varmistaaksemme, ett\u00e4 suunnittelusi on valmis valmistukseen ja kokoonpanoon.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-d9fe223\">\n                        <a href=\"#collapse-1ed4e2c6a045ff1e3765\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-1ed4e2c6a045ff1e3765\" aria-expanded=\"false\" aria-controls=\"Collapse-1ed4e2c6a045ff1e3765\">\n                            \n                            <span class=\"ekit-accordion-title\">Mik\u00e4 on minimim\u00e4\u00e4r\u00e4tilauksesi (MOQ)?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-1ed4e2c6a045ff1e3765\" class=\"collapse\" aria-labelledby=\"primaryHeading-6-d9fe223\" data-parent=\"#accordion-6a045ff1e3765\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Tuemme pienimuotoisia tilauksia alkaen yhdest\u00e4 kappaleesta. Tavallisille PCB:ille ei ole MOQ-rajaa.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-7-d9fe223\">\n                        <a href=\"#collapse-bf72b046a045ff1e3765\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bf72b046a045ff1e3765\" aria-expanded=\"false\" aria-controls=\"Collapse-bf72b046a045ff1e3765\">\n                            \n                            <span class=\"ekit-accordion-title\">Mit\u00e4 maksutapoja hyv\u00e4ksytte?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-left-arrows\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bf72b046a045ff1e3765\" class=\"collapse\" aria-labelledby=\"primaryHeading-7-d9fe223\" data-parent=\"#accordion-6a045ff1e3765\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Hyv\u00e4ksymme T\/T (pankkisiirto), PayPalin ja Western Unionin.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Tuotetiedot Kotisivu Tuote Kuuma tuote Korkea l\u00e4mm\u00f6njohtavuus LED PCBA Valmistettu alumiinipohjamateriaalista ja 2,0 W\/m\u00b7K l\u00e4mm\u00f6njohtavuuden erist\u00e4v\u00e4st\u00e4 kerroksesta, t\u00e4m\u00e4 LED PCBA tarjoaa erinomaisen l\u00e4mm\u00f6nhukan. Ominaisuuksiin kuuluvat 1 oz kuparipaksuus, yksikerroksinen rakenne ja pintak\u00e4sittelyvaihtoehdot kuten HASL tai ENIG. Ihanteellinen korkeatehoisille LED-valaistussovelluksille. Luotettava Turvallisuus Vakaa suorituskyky [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_zeroy_edited":false,"_zeroy_last_edited":"","footnotes":""},"class_list":["post-2152","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ycpcbs.com\/fi\/wp-json\/wp\/v2\/pages\/2152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ycpcbs.com\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ycpcbs.com\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ycpcbs.com\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ycpcbs.com\/fi\/wp-json\/wp\/v2\/comments?post=2152"}],"version-history":[{"count":10,"href":"https:\/\/ycpcbs.com\/fi\/wp-json\/wp\/v2\/pages\/2152\/revisions"}],"predecessor-version":[{"id":2306,"href":"https:\/\/ycpcbs.com\/fi\/wp-json\/wp\/v2\/pages\/2152\/revisions\/2306"}],"wp:attachment":[{"href":"https:\/\/ycpcbs.com\/fi\/wp-json\/wp\/v2\/media?parent=2152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}